{"id":84,"date":"2025-01-24T21:58:52","date_gmt":"2025-01-24T20:58:52","guid":{"rendered":"https:\/\/heilauftrag.de\/?page_id=84"},"modified":"2026-03-13T15:31:44","modified_gmt":"2026-03-13T14:31:44","slug":"ich-bin-das-ich","status":"publish","type":"page","link":"https:\/\/hooponoponosouthafrica.com\/de\/ich-bin-das-ich\/","title":{"rendered":"&#8222;ICH&#8220; bin das &#8222;ICH&#8220;"},"content":{"rendered":"\n<h1 class=\"gb-text gb-text-4fe9a86b\"><strong>&#8222;ICH&#8220; bin das &#8222;ICH&#8220;<\/strong><\/h1>\n\n\n\n<p class=\"has-text-align-center\">\u201eICH\u201d BIN DAS \u201eICH\u201d<br>OWAU NO KA \u201dI\u201d<\/p>\n\n\n\n<p class=\"has-text-align-center\">\u201eIch\u201d komme aus der Leere und trete ins Licht,<br>Pua mai au mai ka po iloko o ka malamalama,<\/p>\n\n\n\n<p class=\"has-text-align-center\">\u201eIch\u201d bin der Atem, der das Leben n\u00e4hrt,<br>Owau no ka ha, ka mauli ola,<\/p>\n\n\n\n<p class=\"has-text-align-center\">\u201eIch\u201d bin jene Leere, jene Hohlheit, jenseits allen Bewusstseins,<br>Owau no ka poho, ke ka\u2019ele mawaho a\u2019e o no ike apau,<\/p>\n\n\n\n<p class=\"has-text-align-center\">Das \u201eIch\u201d, das Id, das Alles.<br>Ka \u201cI\u201d, ke Kino Iho, na Mea Apau.<\/p>\n\n\n\n<p class=\"has-text-align-center\">Mit meinen Bogen aus Regenb\u00f6gen \u00fcberspanne &#8222;Ich&#8220; das Meer,<br>Ka a\u2019e au \u201cI\u201d ku\u2019u pi\u2019o o na anuenue mawaho a\u2019e o na kai apau,<\/p>\n\n\n\n<p class=\"has-text-align-center\">Im Strom der fortgesetzten Wechselwirkung von Geist und Materie.<br>Ka ho\u2019omaumau o na mana\u2019o ame na mea apau.<\/p>\n\n\n\n<p class=\"has-text-align-center\">\u201eIch\u201d bin der ein- und ausstr\u00f6mende Atem,<br>Owau no ka \u201dHo\u201d a me ka \u201dHa\u201d,<\/p>\n\n\n\n<p class=\"has-text-align-center\">Die unsichtbare, unber\u00fchrbare Brise,<br>He huna ka makani nahenahe,<\/p>\n\n\n\n<p class=\"has-text-align-center\">Der unergr\u00fcndliche Urstoff der Sch\u00f6pfung.<br>Ka \u201cHua\u201d huna o Kumulipo.<\/p>\n\n\n\n<p class=\"has-text-align-center\">\u201eIch\u201d bin das \u201eIch\u201d.<br>Owau no ka &#8222;I&#8220;<\/p>\n\n\n\n<p class=\"gb-text gb-text-1af8407f\">Copyright \u00a9 1980 The Foundation of I, Inc. Freedom of the Cosmos<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8222;ICH&#8220; bin das &#8222;ICH&#8220; \u201eICH\u201d BIN DAS \u201eICH\u201dOWAU NO KA \u201dI\u201d \u201eIch\u201d komme aus der Leere und trete ins Licht,Pua mai au mai ka po iloko o ka malamalama, \u201eIch\u201d bin der Atem, der das Leben n\u00e4hrt,Owau no ka ha, ka mauli ola, \u201eIch\u201d bin jene Leere, jene Hohlheit, jenseits allen Bewusstseins,Owau no ka poho, &#8230; <a title=\"&#8222;ICH&#8220; bin das &#8222;ICH&#8220;\" class=\"read-more\" href=\"https:\/\/hooponoponosouthafrica.com\/de\/ich-bin-das-ich\/\" aria-label=\"Mehr Informationen \u00fcber &#8222;ICH&#8220; bin das &#8222;ICH&#8220;\">Weiterlesen<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"slim_seo":{"title":"\"ICH\" bin das \"ICH\" - Ho&#039;oponopono South Africa","description":"\"ICH\" bin das \"ICH\" \u201eICH\u201d BIN DAS \u201eICH\u201d OWAU NO KA \u201dI\u201d \u201eIch\u201d komme aus der Leere und trete ins Licht, Pua mai au mai ka po iloko o ka malamalama, \u201eIch\u201d bin der"},"footnotes":""},"class_list":["post-84","page","type-page","status-publish"],"acf":[],"_links":{"self":[{"href":"https:\/\/hooponoponosouthafrica.com\/de\/wp-json\/wp\/v2\/pages\/84","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hooponoponosouthafrica.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/hooponoponosouthafrica.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/hooponoponosouthafrica.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hooponoponosouthafrica.com\/de\/wp-json\/wp\/v2\/comments?post=84"}],"version-history":[{"count":4,"href":"https:\/\/hooponoponosouthafrica.com\/de\/wp-json\/wp\/v2\/pages\/84\/revisions"}],"predecessor-version":[{"id":879,"href":"https:\/\/hooponoponosouthafrica.com\/de\/wp-json\/wp\/v2\/pages\/84\/revisions\/879"}],"wp:attachment":[{"href":"https:\/\/hooponoponosouthafrica.com\/de\/wp-json\/wp\/v2\/media?parent=84"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}