{"id":80,"date":"2025-01-24T21:58:22","date_gmt":"2025-01-24T20:58:22","guid":{"rendered":"https:\/\/heilauftrag.de\/?page_id=80"},"modified":"2026-04-07T14:50:11","modified_gmt":"2026-04-07T12:50:11","slug":"kontakt","status":"publish","type":"page","link":"https:\/\/hooponoponosouthafrica.com\/de\/kontakt\/","title":{"rendered":"Ihr Kontakt zu uns"},"content":{"rendered":"\n<div class=\"gbp-section gb-element-d28cf48e\">\n<div class=\"gbp-section__inner gb-element-48aef42b\">\n<div class=\"gb-element-da734f86\">\n<p class=\"gb-text\">Haben Sie Fragen zu den Seminaren? \u00dcber das Kontaktformular k\u00f6nnen Sie uns schnell und bequem kontaktieren.<br><br>Oder schicken Sie uns eine WhatsApp-Nachricht: +49 151.401.32845<br><br><br>Informationen von Ho&#8217;oponopono-Germany gibt es auch auf Instagram und YouTube:<br><\/p>\n\n\n\n<div class=\"gb-element-18c2a864\">\n<a class=\"gb-text-b9e230c0\" href=\"https:\/\/web.whatsapp.com\/send?phone=+49015140132845\" target=\"_blank\" rel=\"noopener nofollow\"><span class=\"gb-shape\"><svg aria-hidden=\"true\" role=\"img\" height=\"1em\" width=\"1em\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path fill=\"currentColor\" d=\"M380.9 97.1C339 55.1 283.2 32 223.9 32c-122.4 0-222 99.6-222 222 0 39.1 10.2 77.3 29.6 111L0 480l117.7-30.9c32.4 17.7 68.9 27 106.1 27h.1c122.3 0 224.1-99.6 224.1-222 0-59.3-25.2-115-67.1-157zm-157 341.6c-33.2 0-65.7-8.9-94-25.7l-6.7-4-69.8 18.3L72 359.2l-4.4-7c-18.5-29.4-28.2-63.3-28.2-98.2 0-101.7 82.8-184.5 184.6-184.5 49.3 0 95.6 19.2 130.4 54.1 34.8 34.9 56.2 81.2 56.1 130.5 0 101.8-84.9 184.6-186.6 184.6zm101.2-138.2c-5.5-2.8-32.8-16.2-37.9-18-5.1-1.9-8.8-2.8-12.5 2.8-3.7 5.6-14.3 18-17.6 21.8-3.2 3.7-6.5 4.2-12 1.4-32.6-16.3-54-29.1-75.5-66-5.7-9.8 5.7-9.1 16.3-30.3 1.8-3.7.9-6.9-.5-9.7-1.4-2.8-12.5-30.1-17.1-41.2-4.5-10.8-9.1-9.3-12.5-9.5-3.2-.2-6.9-.2-10.6-.2-3.7 0-9.7 1.4-14.8 6.9-5.1 5.6-19.4 19-19.4 46.3 0 27.3 19.9 53.7 22.6 57.4 2.8 3.7 39.1 59.7 94.8 83.8 35.2 15.2 49 16.5 66.6 13.9 10.7-1.6 32.8-13.4 37.4-26.4 4.6-13 4.6-24.1 3.2-26.4-1.3-2.5-5-3.9-10.5-6.6z\"><\/path><\/svg><\/span><\/a>\n\n\n\n<a class=\"gb-text-a8d1d11a\" href=\"https:\/\/www.instagram.com\/hooponoponogermany\/\" target=\"_blank\" rel=\"noopener nofollow\"><span class=\"gb-shape\"><svg aria-hidden=\"true\" role=\"img\" height=\"1em\" width=\"1em\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path fill=\"currentColor\" d=\"M224.1 141c-63.6 0-114.9 51.3-114.9 114.9s51.3 114.9 114.9 114.9S339 319.5 339 255.9 287.7 141 224.1 141zm0 189.6c-41.1 0-74.7-33.5-74.7-74.7s33.5-74.7 74.7-74.7 74.7 33.5 74.7 74.7-33.6 74.7-74.7 74.7zm146.4-194.3c0 14.9-12 26.8-26.8 26.8-14.9 0-26.8-12-26.8-26.8s12-26.8 26.8-26.8 26.8 12 26.8 26.8zm76.1 27.2c-1.7-35.9-9.9-67.7-36.2-93.9-26.2-26.2-58-34.4-93.9-36.2-37-2.1-147.9-2.1-184.9 0-35.8 1.7-67.6 9.9-93.9 36.1s-34.4 58-36.2 93.9c-2.1 37-2.1 147.9 0 184.9 1.7 35.9 9.9 67.7 36.2 93.9s58 34.4 93.9 36.2c37 2.1 147.9 2.1 184.9 0 35.9-1.7 67.7-9.9 93.9-36.2 26.2-26.2 34.4-58 36.2-93.9 2.1-37 2.1-147.8 0-184.8zM398.8 388c-7.8 19.6-22.9 34.7-42.6 42.6-29.5 11.7-99.5 9-132.1 9s-102.7 2.6-132.1-9c-19.6-7.8-34.7-22.9-42.6-42.6-11.7-29.5-9-99.5-9-132.1s-2.6-102.7 9-132.1c7.8-19.6 22.9-34.7 42.6-42.6 29.5-11.7 99.5-9 132.1-9s102.7-2.6 132.1 9c19.6 7.8 34.7 22.9 42.6 42.6 11.7 29.5 9 99.5 9 132.1s2.7 102.7-9 132.1z\"><\/path><\/svg><\/span><\/a>\n\n\n\n<a class=\"gb-text-60cff3be\" href=\"https:\/\/www.youtube.com\/channel\/UCzdP1w37QDSRNvh8LJ6jKdQ\" target=\"_blank\" rel=\"noopener nofollow\"><span class=\"gb-shape\"><svg aria-hidden=\"true\" role=\"img\" height=\"1em\" width=\"1em\" viewBox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path fill=\"currentColor\" d=\"M549.655 124.083c-6.281-23.65-24.787-42.276-48.284-48.597C458.781 64 288 64 288 64S117.22 64 74.629 75.486c-23.497 6.322-42.003 24.947-48.284 48.597-11.412 42.867-11.412 132.305-11.412 132.305s0 89.438 11.412 132.305c6.281 23.65 24.787 41.5 48.284 47.821C117.22 448 288 448 288 448s170.78 0 213.371-11.486c23.497-6.321 42.003-24.171 48.284-47.821 11.412-42.867 11.412-132.305 11.412-132.305s0-89.438-11.412-132.305zm-317.51 213.508V175.185l142.739 81.205-142.739 81.201z\"><\/path><\/svg><\/span><\/a>\n<\/div>\n<\/div>\n\n\n\n<div><style id=\"wpforms-css-vars-110-block-a257d9ab-5d9c-4ef5-9618-8208ef679c28\">\n\t\t\t\t#wpforms-110.wpforms-block-a257d9ab-5d9c-4ef5-9618-8208ef679c28 {\n\t\t\t\t--wpforms-field-size-input-height: 43px;\n--wpforms-field-size-input-spacing: 15px;\n--wpforms-field-size-font-size: 16px;\n--wpforms-field-size-line-height: 19px;\n--wpforms-field-size-padding-h: 14px;\n--wpforms-field-size-checkbox-size: 16px;\n--wpforms-field-size-sublabel-spacing: 5px;\n--wpforms-field-size-icon-size: 1;\n--wpforms-label-size-font-size: 16px;\n--wpforms-label-size-line-height: 19px;\n--wpforms-label-size-sublabel-font-size: 14px;\n--wpforms-label-size-sublabel-line-height: 17px;\n--wpforms-button-size-font-size: 17px;\n--wpforms-button-size-height: 41px;\n--wpforms-button-size-padding-h: 15px;\n--wpforms-button-size-margin-top: 10px;\n--wpforms-container-shadow-size-box-shadow: none;\n\t\t\t}\n\t\t\t<\/style><div class=\"wpforms-container wpforms-container-full wpforms-block wpforms-block-a257d9ab-5d9c-4ef5-9618-8208ef679c28 wpforms-render-modern\" id=\"wpforms-110\"><form id=\"wpforms-form-110\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"110\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/de\/wp-json\/wp\/v2\/pages\/80\" data-token=\"215617cff1552989ca9e42628aae55a7\" data-token-time=\"1778711103\"><div class=\"wpforms-head-container\"><div class=\"wpforms-title\">Kontakt<\/div><\/div><noscript class=\"wpforms-error-noscript\">Bitte aktiviere JavaScript in deinem Browser, um dieses Formular fertigzustellen.<\/noscript><div id=\"wpforms-error-noscript\" style=\"display: none;\">Bitte aktiviere JavaScript in deinem Browser, um dieses Formular fertigzustellen.<\/div><div class=\"wpforms-field-container\"><div id=\"wpforms-110-field_1-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"1\"><fieldset><legend class=\"wpforms-field-label\">Name <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><div class=\"wpforms-field-row wpforms-field-large\"><div class=\"wpforms-field-row-block wpforms-first wpforms-one-half\"><input type=\"text\" id=\"wpforms-110-field_1\" class=\"wpforms-field-name-first wpforms-field-required\" name=\"wpforms[fields][1][first]\" aria-errormessage=\"wpforms-110-field_1-error\" required><label for=\"wpforms-110-field_1\" class=\"wpforms-field-sublabel after\">Vorname<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half\"><input type=\"text\" id=\"wpforms-110-field_1-last\" class=\"wpforms-field-name-last wpforms-field-required\" name=\"wpforms[fields][1][last]\" aria-errormessage=\"wpforms-110-field_1-last-error\" required><label for=\"wpforms-110-field_1-last\" class=\"wpforms-field-sublabel after\">Nachname<\/label><\/div><\/div><\/fieldset><\/div>\t\t<div id=\"wpforms-110-field_4-container\"\n\t\t\tclass=\"wpforms-field wpforms-field-text\"\n\t\t\tdata-field-type=\"text\"\n\t\t\tdata-field-id=\"4\"\n\t\t\t>\n\t\t\t<label class=\"wpforms-field-label\" for=\"wpforms-110-field_4\" >Ihre Nachricht E-Mail-Adresse<\/label>\n\t\t\t<input type=\"text\" id=\"wpforms-110-field_4\" class=\"wpforms-field-medium\" name=\"wpforms[fields][4]\" >\n\t\t<\/div>\n\t\t<div id=\"wpforms-110-field_2-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"2\"><label class=\"wpforms-field-label\" for=\"wpforms-110-field_2\">E-Mail-Adresse <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"email\" id=\"wpforms-110-field_2\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][2]\" spellcheck=\"false\" aria-errormessage=\"wpforms-110-field_2-error\" required><\/div><div id=\"wpforms-110-field_3-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"3\"><label class=\"wpforms-field-label\" for=\"wpforms-110-field_3\">Ihre Nachricht<\/label><textarea id=\"wpforms-110-field_3\" class=\"wpforms-field-medium\" name=\"wpforms[fields][3]\" aria-errormessage=\"wpforms-110-field_3-error\" ><\/textarea><\/div><script>\n\t\t\t\t( function() {\n\t\t\t\t\tconst style = document.createElement( 'style' );\n\t\t\t\t\tstyle.appendChild( document.createTextNode( '#wpforms-110-field_4-container { position: absolute !important; overflow: hidden !important; display: inline !important; height: 1px !important; width: 1px !important; z-index: -1000 !important; padding: 0 !important; } #wpforms-110-field_4-container input { visibility: hidden; } #wpforms-conversational-form-page #wpforms-110-field_4-container label { counter-increment: none; }' ) );\n\t\t\t\t\tdocument.head.appendChild( style );\n\t\t\t\t\tdocument.currentScript?.remove();\n\t\t\t\t} )();\n\t\t\t<\/script><\/div><!-- .wpforms-field-container --><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"110\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/hooponoponosouthafrica.com\/de\/wp-json\/wp\/v2\/pages\/80\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-110\" class=\"wpforms-submit\" data-alt-text=\"Wird gesendet\u00a0\u2026\" data-submit-text=\"Absenden\" aria-live=\"assertive\" value=\"wpforms-submit\">Absenden<\/button><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/hooponoponosouthafrica.com\/wp-content\/plugins\/wpforms\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Wird geladen\"><\/div><\/form><\/div>  <!-- .wpforms-container --><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"gbp-section gb-element-98eab153\">\n<div class=\"gbp-section__inner gb-element-ec1e2441\">\n<div><\/div>\n\n\n\n<div><style id=\"wpforms-css-vars-113-block-dc36cc6a-a268-48fd-a89f-69fd791279d6\">\n\t\t\t\t#wpforms-113.wpforms-block-dc36cc6a-a268-48fd-a89f-69fd791279d6 {\n\t\t\t\t--wpforms-field-size-input-height: 43px;\n--wpforms-field-size-input-spacing: 15px;\n--wpforms-field-size-font-size: 16px;\n--wpforms-field-size-line-height: 19px;\n--wpforms-field-size-padding-h: 14px;\n--wpforms-field-size-checkbox-size: 16px;\n--wpforms-field-size-sublabel-spacing: 5px;\n--wpforms-field-size-icon-size: 1;\n--wpforms-label-size-font-size: 16px;\n--wpforms-label-size-line-height: 19px;\n--wpforms-label-size-sublabel-font-size: 14px;\n--wpforms-label-size-sublabel-line-height: 17px;\n--wpforms-button-size-font-size: 17px;\n--wpforms-button-size-height: 41px;\n--wpforms-button-size-padding-h: 15px;\n--wpforms-button-size-margin-top: 10px;\n--wpforms-container-shadow-size-box-shadow: none;\n\t\t\t}\n\t\t\t<\/style><div class=\"wpforms-container wpforms-container-full wpforms-block wpforms-block-dc36cc6a-a268-48fd-a89f-69fd791279d6 wpforms-render-modern\" id=\"wpforms-113\"><form id=\"wpforms-form-113\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"113\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/de\/wp-json\/wp\/v2\/pages\/80\" data-token=\"003ba3c5399c8126dcce4717a0f1659c\" data-token-time=\"1778711103\"><div class=\"wpforms-head-container\"><div class=\"wpforms-title\">Newsletteranmeldung<\/div><\/div><noscript class=\"wpforms-error-noscript\">Bitte aktiviere JavaScript in deinem Browser, um dieses Formular fertigzustellen.<\/noscript><div id=\"wpforms-error-noscript\" style=\"display: none;\">Bitte aktiviere JavaScript in deinem Browser, um dieses Formular fertigzustellen.<\/div><div class=\"wpforms-field-container\"><div id=\"wpforms-113-field_1-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"1\"><fieldset><legend class=\"wpforms-field-label\">Name <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><div class=\"wpforms-field-row wpforms-field-large\"><div class=\"wpforms-field-row-block wpforms-first wpforms-one-half\"><input type=\"text\" id=\"wpforms-113-field_1\" class=\"wpforms-field-name-first wpforms-field-required\" name=\"wpforms[fields][1][first]\" aria-errormessage=\"wpforms-113-field_1-error\" required><label for=\"wpforms-113-field_1\" class=\"wpforms-field-sublabel after\">Vorname<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half\"><input type=\"text\" id=\"wpforms-113-field_1-last\" class=\"wpforms-field-name-last wpforms-field-required\" name=\"wpforms[fields][1][last]\" aria-errormessage=\"wpforms-113-field_1-last-error\" required><label for=\"wpforms-113-field_1-last\" class=\"wpforms-field-sublabel after\">Nachname<\/label><\/div><\/div><\/fieldset><\/div>\t\t<div id=\"wpforms-113-field_4-container\"\n\t\t\tclass=\"wpforms-field wpforms-field-text\"\n\t\t\tdata-field-type=\"text\"\n\t\t\tdata-field-id=\"4\"\n\t\t\t>\n\t\t\t<label class=\"wpforms-field-label\" for=\"wpforms-113-field_4\" >Name E-Mail-Adresse DSGVO-Einverst\u00e4ndnis<\/label>\n\t\t\t<input type=\"text\" id=\"wpforms-113-field_4\" class=\"wpforms-field-medium\" name=\"wpforms[fields][4]\" >\n\t\t<\/div>\n\t\t<div id=\"wpforms-113-field_2-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"2\"><label class=\"wpforms-field-label\" for=\"wpforms-113-field_2\">E-Mail-Adresse <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"email\" id=\"wpforms-113-field_2\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][2]\" spellcheck=\"false\" aria-errormessage=\"wpforms-113-field_2-error\" required><\/div><div id=\"wpforms-113-field_3-container\" class=\"wpforms-field wpforms-field-gdpr-checkbox\" data-field-id=\"3\"><label class=\"wpforms-field-label\">DSGVO-Einverst\u00e4ndnis <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><ul id=\"wpforms-113-field_3\" class=\"wpforms-field-required\"><li class=\"choice-1\"><input type=\"checkbox\" id=\"wpforms-113-field_3_1\" name=\"wpforms[fields][3][]\" value=\"Ich m\u00f6chte den Newsletter empfangen und stimme den Datenschutzbestimmungen zu.\" aria-errormessage=\"wpforms-113-field_3_1-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-113-field_3_1\">Ich m\u00f6chte den Newsletter empfangen und stimme den Datenschutzbestimmungen zu.<\/label><\/li><\/ul><\/div><script>\n\t\t\t\t( function() {\n\t\t\t\t\tconst style = document.createElement( 'style' );\n\t\t\t\t\tstyle.appendChild( document.createTextNode( '#wpforms-110-field_4-container,#wpforms-113-field_4-container { position: absolute !important; overflow: hidden !important; display: inline !important; height: 1px !important; width: 1px !important; z-index: -1000 !important; padding: 0 !important; } #wpforms-110-field_4-container,#wpforms-113-field_4-container input { visibility: hidden; } #wpforms-conversational-form-page #wpforms-110-field_4-container,#wpforms-113-field_4-container label { counter-increment: none; }' ) );\n\t\t\t\t\tdocument.head.appendChild( style );\n\t\t\t\t\tdocument.currentScript?.remove();\n\t\t\t\t} )();\n\t\t\t<\/script><\/div><!-- .wpforms-field-container --><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"113\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/hooponoponosouthafrica.com\/de\/wp-json\/wp\/v2\/pages\/80\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-113\" class=\"wpforms-submit\" data-alt-text=\"Wird gesendet\u00a0\u2026\" data-submit-text=\"Absenden\" aria-live=\"assertive\" value=\"wpforms-submit\">Absenden<\/button><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/hooponoponosouthafrica.com\/wp-content\/plugins\/wpforms\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Wird geladen\"><\/div><\/form><\/div>  <!-- .wpforms-container --><\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Haben Sie Fragen zu den Seminaren? \u00dcber das Kontaktformular k\u00f6nnen Sie uns schnell und bequem kontaktieren. Oder schicken Sie uns eine WhatsApp-Nachricht: +49 151.401.32845 Informationen von Ho&#8217;oponopono-Germany gibt es auch auf Instagram und YouTube:<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"slim_seo":{"title":"Ihr Kontakt zu uns - Ho&#039;oponopono South Africa","description":"Haben Sie Fragen zu den Seminaren? \u00dcber das Kontaktformular k\u00f6nnen Sie uns schnell und bequem kontaktieren. Oder schicken Sie uns eine WhatsApp-Nachricht: +49 1"},"footnotes":""},"class_list":["post-80","page","type-page","status-publish"],"acf":[],"_links":{"self":[{"href":"https:\/\/hooponoponosouthafrica.com\/de\/wp-json\/wp\/v2\/pages\/80","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hooponoponosouthafrica.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/hooponoponosouthafrica.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/hooponoponosouthafrica.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hooponoponosouthafrica.com\/de\/wp-json\/wp\/v2\/comments?post=80"}],"version-history":[{"count":7,"href":"https:\/\/hooponoponosouthafrica.com\/de\/wp-json\/wp\/v2\/pages\/80\/revisions"}],"predecessor-version":[{"id":960,"href":"https:\/\/hooponoponosouthafrica.com\/de\/wp-json\/wp\/v2\/pages\/80\/revisions\/960"}],"wp:attachment":[{"href":"https:\/\/hooponoponosouthafrica.com\/de\/wp-json\/wp\/v2\/media?parent=80"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}